{"id":22160,"date":"2026-07-13T12:45:20","date_gmt":"2026-07-13T10:45:20","guid":{"rendered":"https:\/\/rheinhessen-news.de\/news\/?p=22160"},"modified":"2026-07-13T12:45:21","modified_gmt":"2026-07-13T10:45:21","slug":"landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung","status":"publish","type":"post","link":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/","title":{"rendered":"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung"},"content":{"rendered":"<div class=\"rhein-vor-dem-inhalt\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"rhein-2443085003\" data-cfpa=\"16996\" data-cfpw=\"16996\"><div class=\"rhein-adlabel\">Werbung<\/div><a href=\"https:\/\/a.check24.net\/misc\/click.php?pid=302210&aid=341&cat=14\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/a.check24.net\/misc\/view.php?pid=302210&aid=341&cat=14\" width=\"1200\" height=\"300\" style=\"max-width: 100%; height: auto;\" ><\/a><\/div><script type=\"text\/javascript\">;new advadsCfpAd( 16996 );<\/script>\n<p><strong>ALZEY (red\/kvaz\/f) &#8211;<\/strong> Im Rahmen einer Feierstunde begr\u00fc\u00dfte Landrat Heiko Sippel zahlreiche neue wie auch langj\u00e4hrige Mitarbeitende der Kreisverwaltung Alzey-Worms. Er betonte: \u201eDie Kreisverwaltung ist ein gro\u00dfes Team mit unterschiedlichen Talenten und St\u00e4rken, die sich sehr gut erg\u00e4nzen. Dieses Zusammenspiel macht unsere Arbeit aus. Unser Miteinander entsteht durch das gegenseitige Motivieren.\u201c<\/p>\n\n\n\n<p>Unter den neuen Mitarbeitenden befanden sich Aurelia Cirullo, Emily Dauth und Tim Steiner, die durch den Landrat feierlich zu Kreisinspektoranw\u00e4rter*innen ernannt wurden. Im Zuge ihres dreij\u00e4hrigen Vorbereitungsdienstes werden sie die Hochschule f\u00fcr \u00f6ffentliche Verwaltung in Mayen besuchen. \u201eMayen ist das Trainingslager\u201c, erkl\u00e4rte Landrat Sippel. Im Anschluss an einen jeden Studienabschnitt kann das neu erlernte Wissen w\u00e4hrend der Praxisphasen in den verschiedenen Abteilungen der Kreisverwaltung angewendet werden.<\/p>\n\n\n\n<p>Mit Bravour gemeistert haben das \u201eTrainingslager\u201c Kevin Metz und Leona Schulz. Sippel gratulierte zu ihren Bachelorabschl\u00fcssen und dem damit vollendeten Vorbereitungsdienst. Der Kreischef ernannte Metz und Schulz zu Kreisinspektoren. Ihren Dienst werden Metz in der Unteren Wasserbeh\u00f6rde und Schulz in der Einb\u00fcrgerungsbeh\u00f6rde verrichten.<\/p>\n\n\n\n<p>Ebenfalls Grund zum Feiern hatten: Emely Barth, Paul Ferling, Ruth G\u00f6rsch, Finn Hassinger und Nevin Mamakalo. Die Nachwuchskr\u00e4fte haben ihre Ausbildungen zu Verwaltungsfachangestellten, Kaufleuten f\u00fcr Digitalisierungsmanagement sowie Fachinformatiker f\u00fcr Systemintegration erfolgreich abgeschlossen. Landrat Sippel gratulierte ihnen zu ihren Leistungen und freute sich, allen eine \u00dcbernahme zusichern zu k\u00f6nnen. Die Gleichstellungsbeauftragte Dr. Vera Lanzen sowie die stellvertretende Personalratsvorsitzende Kerstin Brand schlossen sich den Gl\u00fcckw\u00fcnschen an.<\/p>\n\n\n\n<p><strong>25 Jahre im Dienst des Krankenhauses<\/strong><\/p>\n\n\n\n<p>Im Beisein des Verwaltungsdirektors Frank M\u00fcller und des Personalratsvorsitzenden Andreas Barwig, feierte Ines Loch, Mitarbeitende des Kreiskrankenhauses ihr 25-j\u00e4hriges Dienstjubil\u00e4um.<\/p>\n\n\n\n<p>\u201eHerzlichen Dank im Namen des Landkreises wie auch pers\u00f6nlich f\u00fcr Ihre jahrelange Treue zum heutigen Kreiskrankenhaus\u201c, sagte Landrat Heiko Sippel und gratulierte Loch zum Jubil\u00e4um. Die gelernte B\u00fcrokraft begann ihre berufliche Laufbahn im heutigen Kreiskrankenhaus 2001 mit ihrer Einstellung als Mitarbeiterin f\u00fcr den \u00e4rztlichen Schreibdienst. In den vergangen 25 Jahren durchlief sie in ihrer T\u00e4tigkeit im Kreiskrankenhaus verschiedene Stationen. Mit dem Beginn der Altersrente 2026, entschloss sich Loch weiterhin im \u00e4rztlichen Schreibdienst t\u00e4tig zu bleiben. Sippel \u00fcberreichte Loch zum Dank eine Urkunde. (Quelle: Kreisverwaltung Alzey-Worms)<\/p>\n<div class=\"rhein-nach-dem-inhalt\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"rhein-3954172880\" data-cfpa=\"16994\" data-cfpw=\"16994\"><div class=\"rhein-adlabel\">Werbung<\/div><a href=\"https:\/\/www.willius-senzer.de\/\" aria-label=\"selzer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/07\/selzer.png\" alt=\"\"  srcset=\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/07\/selzer.png 640w, https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/07\/selzer-300x82.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" width=\"640\" height=\"174\"  style=\"opacity: 1 !important;\" \/><\/a><\/div><script type=\"text\/javascript\">;new advadsCfpAd( 16994 );<\/script>","protected":false},"excerpt":{"rendered":"<p>ALZEY (red\/kvaz\/f) &#8211; Im Rahmen einer Feierstunde begr\u00fc\u00dfte Landrat Heiko Sippel zahlreiche neue wie auch langj\u00e4hrige Mitarbeitende der Kreisverwaltung Alzey-Worms. Er betonte: \u201eDie Kreisverwaltung ist ein gro\u00dfes Team mit unterschiedlichen Talenten und St\u00e4rken, die sich sehr gut erg\u00e4nzen. Dieses Zusammenspiel macht unsere Arbeit aus. Unser Miteinander entsteht durch das gegenseitige Motivieren.\u201c Unter den neuen Mitarbeitenden [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,26],"tags":[],"class_list":{"0":"post-22160","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-alzey-worms","8":"category-regional"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung - Rheinhessen News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung - Rheinhessen News\" \/>\n<meta property=\"og:description\" content=\"ALZEY (red\/kvaz\/f) &#8211; Im Rahmen einer Feierstunde begr\u00fc\u00dfte Landrat Heiko Sippel zahlreiche neue wie auch langj\u00e4hrige Mitarbeitende der Kreisverwaltung Alzey-Worms. Er betonte: \u201eDie Kreisverwaltung ist ein gro\u00dfes Team mit unterschiedlichen Talenten und St\u00e4rken, die sich sehr gut erg\u00e4nzen. Dieses Zusammenspiel macht unsere Arbeit aus. Unser Miteinander entsteht durch das gegenseitige Motivieren.\u201c Unter den neuen Mitarbeitenden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/\" \/>\n<meta property=\"og:site_name\" content=\"Rheinhessen News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rheinhessennews\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T10:45:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T10:45:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/\",\"url\":\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/\",\"name\":\"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung - Rheinhessen News\",\"isPartOf\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg\",\"datePublished\":\"2026-07-13T10:45:20+00:00\",\"dateModified\":\"2026-07-13T10:45:21+00:00\",\"author\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/cc34ffc7610606e70f65289eee180407\"},\"breadcrumb\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#primaryimage\",\"url\":\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg\",\"contentUrl\":\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"Landrat Heiko Sippel (2.v.l.), Verwaltungsdirektor des Kreiskrankenhaus Frank M\u00fcller (l.), Personalratsvorsitzender des Kreiskrankenhaus Andreas Barwig (3.v.l.), die Gleichstellungsbeauftragte Dr. Vera Lanzen (2.v.r.) und die stellvertretende Personalratsvorsitzende Kerstin Brand (r.) gratulierten der Jubilarin Ines Loch. (Foto: D\u00e9sir\u00e9e Weinl\u00e4nder \/ Kreisverwaltung Alzey-Worms)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rheinhessen-news.de\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#website\",\"url\":\"https:\/\/rheinhessen-news.de\/news\/\",\"name\":\"Rheinhessen News\",\"description\":\"Aus Rheinhessen - f\u00fcr Rheinhessen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rheinhessen-news.de\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/cc34ffc7610606e70f65289eee180407\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e44e11f3fb7b58f16cc1a1ad8200f43?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e44e11f3fb7b58f16cc1a1ad8200f43?s=96&d=blank&r=g\",\"caption\":\"Redaktion\"},\"sameAs\":[\"http:\/\/www.rheinhessen-news.de\"],\"url\":\"https:\/\/rheinhessen-news.de\/news\/author\/jeremy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung - Rheinhessen News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/","og_locale":"de_DE","og_type":"article","og_title":"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung - Rheinhessen News","og_description":"ALZEY (red\/kvaz\/f) &#8211; Im Rahmen einer Feierstunde begr\u00fc\u00dfte Landrat Heiko Sippel zahlreiche neue wie auch langj\u00e4hrige Mitarbeitende der Kreisverwaltung Alzey-Worms. Er betonte: \u201eDie Kreisverwaltung ist ein gro\u00dfes Team mit unterschiedlichen Talenten und St\u00e4rken, die sich sehr gut erg\u00e4nzen. Dieses Zusammenspiel macht unsere Arbeit aus. Unser Miteinander entsteht durch das gegenseitige Motivieren.\u201c Unter den neuen Mitarbeitenden [&hellip;]","og_url":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/","og_site_name":"Rheinhessen News","article_publisher":"https:\/\/www.facebook.com\/rheinhessennews","article_published_time":"2026-07-13T10:45:20+00:00","article_modified_time":"2026-07-13T10:45:21+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/","url":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/","name":"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung - Rheinhessen News","isPartOf":{"@id":"https:\/\/rheinhessen-news.de\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#primaryimage"},"image":{"@id":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg","datePublished":"2026-07-13T10:45:20+00:00","dateModified":"2026-07-13T10:45:21+00:00","author":{"@id":"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/cc34ffc7610606e70f65289eee180407"},"breadcrumb":{"@id":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#primaryimage","url":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg","contentUrl":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2026\/07\/Feierstunde-scaled.jpg","width":1920,"height":2560,"caption":"Landrat Heiko Sippel (2.v.l.), Verwaltungsdirektor des Kreiskrankenhaus Frank M\u00fcller (l.), Personalratsvorsitzender des Kreiskrankenhaus Andreas Barwig (3.v.l.), die Gleichstellungsbeauftragte Dr. Vera Lanzen (2.v.r.) und die stellvertretende Personalratsvorsitzende Kerstin Brand (r.) gratulierten der Jubilarin Ines Loch. (Foto: D\u00e9sir\u00e9e Weinl\u00e4nder \/ Kreisverwaltung Alzey-Worms)"},{"@type":"BreadcrumbList","@id":"https:\/\/rheinhessen-news.de\/news\/2026\/07\/13\/landrat-sippel-begruesst-neue-und-gratuliert-verdienten-mitarbeitenden-der-kreisverwaltung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rheinhessen-news.de\/news\/"},{"@type":"ListItem","position":2,"name":"Landrat Sippel begr\u00fc\u00dft neue und gratuliert verdienten Mitarbeitenden der Kreisverwaltung"}]},{"@type":"WebSite","@id":"https:\/\/rheinhessen-news.de\/news\/#website","url":"https:\/\/rheinhessen-news.de\/news\/","name":"Rheinhessen News","description":"Aus Rheinhessen - f\u00fcr Rheinhessen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rheinhessen-news.de\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/cc34ffc7610606e70f65289eee180407","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0e44e11f3fb7b58f16cc1a1ad8200f43?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e44e11f3fb7b58f16cc1a1ad8200f43?s=96&d=blank&r=g","caption":"Redaktion"},"sameAs":["http:\/\/www.rheinhessen-news.de"],"url":"https:\/\/rheinhessen-news.de\/news\/author\/jeremy\/"}]}},"_links":{"self":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts\/22160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/comments?post=22160"}],"version-history":[{"count":1,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts\/22160\/revisions"}],"predecessor-version":[{"id":22162,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts\/22160\/revisions\/22162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/media\/22161"}],"wp:attachment":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/media?parent=22160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/categories?post=22160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/tags?post=22160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}