{"id":15882,"date":"2023-01-23T12:58:05","date_gmt":"2023-01-23T11:58:05","guid":{"rendered":"https:\/\/rheinhessen-news.de\/news\/?p=15882"},"modified":"2023-01-23T12:59:20","modified_gmt":"2023-01-23T11:59:20","slug":"verkehrsunfall-mit-7-verletzten","status":"publish","type":"post","link":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/","title":{"rendered":"Verkehrsunfall mit  sieben Verletzten"},"content":{"rendered":"<div class=\"rhein-vor-dem-inhalt\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"rhein-3980911640\" data-cfpa=\"16996\" data-cfpw=\"16996\"><div class=\"rhein-adlabel\">Werbung<\/div><a href=\"https:\/\/a.check24.net\/misc\/click.php?pid=302210&aid=341&cat=14\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/a.check24.net\/misc\/view.php?pid=302210&aid=341&cat=14\" width=\"1200\" height=\"300\" style=\"max-width: 100%; height: auto;\" ><\/a><\/div><script type=\"text\/javascript\">;new advadsCfpAd( 16996 );<\/script>\n<p><strong>INGELHEIM (jk)- <\/strong>Heute gegen 07:35 Uhr wurde die Polizeiautobahnstation Heidesheim \u00fcber einen Verkehrsunfall mit mehreren beteiligten Fahrzeugen auf der A60, H\u00f6he Anschlussstelle Ingelheim-Ost, informiert. <\/p>\n\n\n\n<p>Wie die Polizei vor Ort feststellen konnte, war es zum Zusammensto\u00df von 5 PKW gekommen. Insgesamt 7 Insassen der Fahrzeuge waren leicht verletzt. Die Richtungsfahrbahn Darmstadt wurde gesperrt. Der Verkehr konnte \u00fcber die Abfahrt Ingelheim-Ost abgeleitet werden. Trotzdem kam es zu erheblichem R\u00fcckstau. Nach ersten Ermittlungen kam es zu einem Auffahrunfall mit drei beteiligten Fahrzeugen. Zwei weitere Fahrzeuge fuhren anschlie\u00dfend auf die verunfallten Fahrzeuge auf. Feuerwehr und Rettungsdienst waren mit mehreren Fahrzeugen im Einsatz. 5 Personen wurden zur weiteren Behandlung in umliegende Krankenh\u00e4user verbracht. 3 Fahrzeuge mussten abgeschleppt werden. Gegen 09:20 Uhr wurde die Fahrbahn wieder freigegeben.<\/p>\n\n\n\n<p>Quelle: Verkehrsdirektion Mainz <\/p>\n<div class=\"rhein-nach-dem-inhalt\" style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"rhein-4170045156\" data-cfpa=\"16994\" data-cfpw=\"16994\"><div class=\"rhein-adlabel\">Werbung<\/div><a href=\"https:\/\/www.willius-senzer.de\/\" aria-label=\"selzer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/07\/selzer.png\" alt=\"\"  srcset=\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/07\/selzer.png 640w, https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/07\/selzer-300x82.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" width=\"640\" height=\"174\"  style=\"opacity: 1 !important;\" \/><\/a><\/div><script type=\"text\/javascript\">;new advadsCfpAd( 16994 );<\/script>","protected":false},"excerpt":{"rendered":"<p>INGELHEIM (jk)- Heute gegen 07:35 Uhr wurde die Polizeiautobahnstation Heidesheim \u00fcber einen Verkehrsunfall mit mehreren beteiligten Fahrzeugen auf der A60, H\u00f6he Anschlussstelle Ingelheim-Ost, informiert. Wie die Polizei vor Ort feststellen konnte, war es zum Zusammensto\u00df von 5 PKW gekommen. Insgesamt 7 Insassen der Fahrzeuge waren leicht verletzt. Die Richtungsfahrbahn Darmstadt wurde gesperrt. Der Verkehr konnte [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":15883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,1,29,26],"tags":[],"class_list":{"0":"post-15882","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-112blaulicht","8":"category-allgemein","9":"category-mainz-bingen","10":"category-regional"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Verkehrsunfall mit sieben Verletzten - Rheinhessen News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verkehrsunfall mit sieben Verletzten - Rheinhessen News\" \/>\n<meta property=\"og:description\" content=\"INGELHEIM (jk)- Heute gegen 07:35 Uhr wurde die Polizeiautobahnstation Heidesheim \u00fcber einen Verkehrsunfall mit mehreren beteiligten Fahrzeugen auf der A60, H\u00f6he Anschlussstelle Ingelheim-Ost, informiert. Wie die Polizei vor Ort feststellen konnte, war es zum Zusammensto\u00df von 5 PKW gekommen. Insgesamt 7 Insassen der Fahrzeuge waren leicht verletzt. Die Richtungsfahrbahn Darmstadt wurde gesperrt. Der Verkehr konnte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/\" \/>\n<meta property=\"og:site_name\" content=\"Rheinhessen News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rheinhessennews\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-23T11:58:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T11:59:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"710\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J. K\u00f6nig\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"J. K\u00f6nig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/\",\"url\":\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/\",\"name\":\"Verkehrsunfall mit sieben Verletzten - Rheinhessen News\",\"isPartOf\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg\",\"datePublished\":\"2023-01-23T11:58:05+00:00\",\"dateModified\":\"2023-01-23T11:59:20+00:00\",\"author\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/74bd3dc90f06d64686344dd2fb6ef0af\"},\"breadcrumb\":{\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#primaryimage\",\"url\":\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg\",\"contentUrl\":\"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg\",\"width\":710,\"height\":533,\"caption\":\"Foto der Unfallstelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rheinhessen-news.de\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verkehrsunfall mit sieben Verletzten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#website\",\"url\":\"https:\/\/rheinhessen-news.de\/news\/\",\"name\":\"Rheinhessen News\",\"description\":\"Aus Rheinhessen - f\u00fcr Rheinhessen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rheinhessen-news.de\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/74bd3dc90f06d64686344dd2fb6ef0af\",\"name\":\"J. K\u00f6nig\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/da2b5630aaa0296731c7317395c962ce?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/da2b5630aaa0296731c7317395c962ce?s=96&d=blank&r=g\",\"caption\":\"J. K\u00f6nig\"},\"url\":\"https:\/\/rheinhessen-news.de\/news\/author\/jessy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verkehrsunfall mit sieben Verletzten - Rheinhessen News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/","og_locale":"de_DE","og_type":"article","og_title":"Verkehrsunfall mit sieben Verletzten - Rheinhessen News","og_description":"INGELHEIM (jk)- Heute gegen 07:35 Uhr wurde die Polizeiautobahnstation Heidesheim \u00fcber einen Verkehrsunfall mit mehreren beteiligten Fahrzeugen auf der A60, H\u00f6he Anschlussstelle Ingelheim-Ost, informiert. Wie die Polizei vor Ort feststellen konnte, war es zum Zusammensto\u00df von 5 PKW gekommen. Insgesamt 7 Insassen der Fahrzeuge waren leicht verletzt. Die Richtungsfahrbahn Darmstadt wurde gesperrt. Der Verkehr konnte [&hellip;]","og_url":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/","og_site_name":"Rheinhessen News","article_publisher":"https:\/\/www.facebook.com\/rheinhessennews","article_published_time":"2023-01-23T11:58:05+00:00","article_modified_time":"2023-01-23T11:59:20+00:00","og_image":[{"width":710,"height":533,"url":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg","type":"image\/jpeg"}],"author":"J. K\u00f6nig","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"J. K\u00f6nig","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/","url":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/","name":"Verkehrsunfall mit sieben Verletzten - Rheinhessen News","isPartOf":{"@id":"https:\/\/rheinhessen-news.de\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#primaryimage"},"image":{"@id":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#primaryimage"},"thumbnailUrl":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg","datePublished":"2023-01-23T11:58:05+00:00","dateModified":"2023-01-23T11:59:20+00:00","author":{"@id":"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/74bd3dc90f06d64686344dd2fb6ef0af"},"breadcrumb":{"@id":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#primaryimage","url":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg","contentUrl":"https:\/\/rheinhessen-news.de\/news\/wp-content\/uploads\/2023\/01\/pol-vdmz-ingelheim-a60-verkehrsunfall-mit-7-verletzten.jpeg","width":710,"height":533,"caption":"Foto der Unfallstelle"},{"@type":"BreadcrumbList","@id":"https:\/\/rheinhessen-news.de\/news\/2023\/01\/23\/verkehrsunfall-mit-7-verletzten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rheinhessen-news.de\/news\/"},{"@type":"ListItem","position":2,"name":"Verkehrsunfall mit sieben Verletzten"}]},{"@type":"WebSite","@id":"https:\/\/rheinhessen-news.de\/news\/#website","url":"https:\/\/rheinhessen-news.de\/news\/","name":"Rheinhessen News","description":"Aus Rheinhessen - f\u00fcr Rheinhessen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rheinhessen-news.de\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/74bd3dc90f06d64686344dd2fb6ef0af","name":"J. K\u00f6nig","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rheinhessen-news.de\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/da2b5630aaa0296731c7317395c962ce?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/da2b5630aaa0296731c7317395c962ce?s=96&d=blank&r=g","caption":"J. K\u00f6nig"},"url":"https:\/\/rheinhessen-news.de\/news\/author\/jessy\/"}]}},"_links":{"self":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts\/15882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/comments?post=15882"}],"version-history":[{"count":2,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts\/15882\/revisions"}],"predecessor-version":[{"id":15885,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/posts\/15882\/revisions\/15885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/media\/15883"}],"wp:attachment":[{"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/media?parent=15882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/categories?post=15882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rheinhessen-news.de\/news\/wp-json\/wp\/v2\/tags?post=15882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}